{"id":80,"count":6,"description":"","link":"https:\/\/gpsmonacogroup.com\/it\/gamme\/electromenager-2\/entretien-nettoyage\/","name":"Manutenzione e pulizia","slug":"entretien-nettoyage","taxonomy":"gamme","parent":134,"meta":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Produits d&#039;entretien et nettoyage - GPS Monaco Group<\/title>\n<meta name=\"description\" content=\"D\u00e9couvrez nos solutions d&#039;entretien et nettoyage pour des \u00e9quipements efficaces et garder votre maison propre et impeccable. Parcourez nos catalogues.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/gpsmonacogroup.com\/it\/gamme\/electromenager-2\/entretien-nettoyage\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Produits d&#039;entretien et nettoyage - GPS Monaco Group\" \/>\n<meta property=\"og:description\" content=\"D\u00e9couvrez nos solutions d&#039;entretien et nettoyage pour des \u00e9quipements efficaces et garder votre maison propre et impeccable. Parcourez nos catalogues.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/gpsmonacogroup.com\/it\/gamme\/electromenager-2\/entretien-nettoyage\/\" \/>\n<meta property=\"og:site_name\" content=\"GPS Monaco Group\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/gpsmonacogroup.com\\\/gamme\\\/electromenager-2\\\/entretien-nettoyage\\\/\",\"url\":\"https:\\\/\\\/gpsmonacogroup.com\\\/gamme\\\/electromenager-2\\\/entretien-nettoyage\\\/\",\"name\":\"Produits d'entretien et nettoyage - GPS Monaco Group\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/gpsmonacogroup.com\\\/it\\\/#website\"},\"description\":\"D\u00e9couvrez nos solutions d'entretien et nettoyage pour des \u00e9quipements efficaces et garder votre maison propre et impeccable. Parcourez nos catalogues.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/gpsmonacogroup.com\\\/gamme\\\/electromenager-2\\\/entretien-nettoyage\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/gpsmonacogroup.com\\\/gamme\\\/electromenager-2\\\/entretien-nettoyage\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/gpsmonacogroup.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00c9lectrom\u00e9nager\",\"item\":\"https:\\\/\\\/gpsmonacogroup.com\\\/gamme\\\/electromenager-2\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Entretien et Nettoyage\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/gpsmonacogroup.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/gpsmonacogroup.com\\\/it\\\/\",\"name\":\"GPS Monaco Group\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/gpsmonacogroup.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/gpsmonacogroup.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/gpsmonacogroup.com\\\/it\\\/#organization\",\"name\":\"GPS Monaco Group\",\"url\":\"https:\\\/\\\/gpsmonacogroup.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/gpsmonacogroup.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/gpsmonacogroup.com\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/logo-GPS-blanc.webp\",\"contentUrl\":\"https:\\\/\\\/gpsmonacogroup.com\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/logo-GPS-blanc.webp\",\"width\":211,\"height\":125,\"caption\":\"GPS Monaco Group\"},\"image\":{\"@id\":\"https:\\\/\\\/gpsmonacogroup.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Produits d'entretien et nettoyage - GPS Monaco Group","description":"D\u00e9couvrez nos solutions d'entretien et nettoyage pour des \u00e9quipements efficaces et garder votre maison propre et impeccable. Parcourez nos catalogues.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/gpsmonacogroup.com\/it\/gamme\/electromenager-2\/entretien-nettoyage\/","og_locale":"it_IT","og_type":"article","og_title":"Produits d'entretien et nettoyage - GPS Monaco Group","og_description":"D\u00e9couvrez nos solutions d'entretien et nettoyage pour des \u00e9quipements efficaces et garder votre maison propre et impeccable. Parcourez nos catalogues.","og_url":"https:\/\/gpsmonacogroup.com\/it\/gamme\/electromenager-2\/entretien-nettoyage\/","og_site_name":"GPS Monaco Group","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/gpsmonacogroup.com\/gamme\/electromenager-2\/entretien-nettoyage\/","url":"https:\/\/gpsmonacogroup.com\/gamme\/electromenager-2\/entretien-nettoyage\/","name":"Produits d'entretien et nettoyage - GPS Monaco Group","isPartOf":{"@id":"https:\/\/gpsmonacogroup.com\/it\/#website"},"description":"D\u00e9couvrez nos solutions d'entretien et nettoyage pour des \u00e9quipements efficaces et garder votre maison propre et impeccable. Parcourez nos catalogues.","breadcrumb":{"@id":"https:\/\/gpsmonacogroup.com\/gamme\/electromenager-2\/entretien-nettoyage\/#breadcrumb"},"inLanguage":"it-IT"},{"@type":"BreadcrumbList","@id":"https:\/\/gpsmonacogroup.com\/gamme\/electromenager-2\/entretien-nettoyage\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/gpsmonacogroup.com\/"},{"@type":"ListItem","position":2,"name":"\u00c9lectrom\u00e9nager","item":"https:\/\/gpsmonacogroup.com\/gamme\/electromenager-2\/"},{"@type":"ListItem","position":3,"name":"Entretien et Nettoyage"}]},{"@type":"WebSite","@id":"https:\/\/gpsmonacogroup.com\/it\/#website","url":"https:\/\/gpsmonacogroup.com\/it\/","name":"Gruppo GPS Monaco","description":"","publisher":{"@id":"https:\/\/gpsmonacogroup.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/gpsmonacogroup.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/gpsmonacogroup.com\/it\/#organization","name":"Gruppo GPS Monaco","url":"https:\/\/gpsmonacogroup.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/gpsmonacogroup.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/gpsmonacogroup.com\/wp-content\/uploads\/2024\/08\/logo-GPS-blanc.webp","contentUrl":"https:\/\/gpsmonacogroup.com\/wp-content\/uploads\/2024\/08\/logo-GPS-blanc.webp","width":211,"height":125,"caption":"GPS Monaco Group"},"image":{"@id":"https:\/\/gpsmonacogroup.com\/it\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/gpsmonacogroup.com\/it\/wp-json\/wp\/v2\/https:\/\/gpsmonacogroup.com\/gamme\/80","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gpsmonacogroup.com\/it\/wp-json\/wp\/v2\/https:\/\/gpsmonacogroup.com\/gamme"}],"about":[{"href":"https:\/\/gpsmonacogroup.com\/it\/wp-json\/wp\/v2\/taxonomies\/gamme"}],"up":[{"embeddable":true,"href":"https:\/\/gpsmonacogroup.com\/it\/wp-json\/wp\/v2\/https:\/\/gpsmonacogroup.com\/gamme\/134"}],"wp:post_type":[{"href":"https:\/\/gpsmonacogroup.com\/it\/wp-json\/wp\/v2\/catalogues?https:\/\/gpsmonacogroup.com\/gamme=80"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}