{"id":143,"count":2,"description":"","link":"https:\/\/gpsmonacogroup.com\/it\/gamme\/medical\/masques-et-charlottes\/","name":"Maschere e Charlottes","slug":"masques-et-charlottes","taxonomy":"gamme","parent":94,"meta":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Masques et charlottes hygi\u00e9niques \u2013 Protection m\u00e9dicale - GPS Monaco Group<\/title>\n<meta name=\"description\" content=\"D\u00e9couvrez nos masques et charlottes hygi\u00e9niques, conformes aux exigences m\u00e9dicales, pour garantir protection et s\u00e9curit\u00e9 dans tous les environnements.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/gpsmonacogroup.com\/it\/gamme\/medical\/masques-et-charlottes\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Masques et charlottes hygi\u00e9niques \u2013 Protection m\u00e9dicale - GPS Monaco Group\" \/>\n<meta property=\"og:description\" content=\"D\u00e9couvrez nos masques et charlottes hygi\u00e9niques, conformes aux exigences m\u00e9dicales, pour garantir protection et s\u00e9curit\u00e9 dans tous les environnements.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/gpsmonacogroup.com\/it\/gamme\/medical\/masques-et-charlottes\/\" \/>\n<meta property=\"og:site_name\" content=\"GPS Monaco Group\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/gpsmonacogroup.com\\\/gamme\\\/medical\\\/masques-et-charlottes\\\/\",\"url\":\"https:\\\/\\\/gpsmonacogroup.com\\\/gamme\\\/medical\\\/masques-et-charlottes\\\/\",\"name\":\"Masques et charlottes hygi\u00e9niques \u2013 Protection m\u00e9dicale - GPS Monaco Group\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/gpsmonacogroup.com\\\/it\\\/#website\"},\"description\":\"D\u00e9couvrez nos masques et charlottes hygi\u00e9niques, conformes aux exigences m\u00e9dicales, pour garantir protection et s\u00e9curit\u00e9 dans tous les environnements.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/gpsmonacogroup.com\\\/gamme\\\/medical\\\/masques-et-charlottes\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/gpsmonacogroup.com\\\/gamme\\\/medical\\\/masques-et-charlottes\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/gpsmonacogroup.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mat\u00e9riel M\u00e9dical\",\"item\":\"https:\\\/\\\/gpsmonacogroup.com\\\/gamme\\\/medical\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Masques et Charlottes\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/gpsmonacogroup.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/gpsmonacogroup.com\\\/it\\\/\",\"name\":\"GPS Monaco Group\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/gpsmonacogroup.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/gpsmonacogroup.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/gpsmonacogroup.com\\\/it\\\/#organization\",\"name\":\"GPS Monaco Group\",\"url\":\"https:\\\/\\\/gpsmonacogroup.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/gpsmonacogroup.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/gpsmonacogroup.com\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/logo-GPS-blanc.webp\",\"contentUrl\":\"https:\\\/\\\/gpsmonacogroup.com\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/logo-GPS-blanc.webp\",\"width\":211,\"height\":125,\"caption\":\"GPS Monaco Group\"},\"image\":{\"@id\":\"https:\\\/\\\/gpsmonacogroup.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Masques et charlottes hygi\u00e9niques \u2013 Protection m\u00e9dicale - GPS Monaco Group","description":"D\u00e9couvrez nos masques et charlottes hygi\u00e9niques, conformes aux exigences m\u00e9dicales, pour garantir protection et s\u00e9curit\u00e9 dans tous les environnements.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/gpsmonacogroup.com\/it\/gamme\/medical\/masques-et-charlottes\/","og_locale":"it_IT","og_type":"article","og_title":"Masques et charlottes hygi\u00e9niques \u2013 Protection m\u00e9dicale - GPS Monaco Group","og_description":"D\u00e9couvrez nos masques et charlottes hygi\u00e9niques, conformes aux exigences m\u00e9dicales, pour garantir protection et s\u00e9curit\u00e9 dans tous les environnements.","og_url":"https:\/\/gpsmonacogroup.com\/it\/gamme\/medical\/masques-et-charlottes\/","og_site_name":"GPS Monaco Group","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/gpsmonacogroup.com\/gamme\/medical\/masques-et-charlottes\/","url":"https:\/\/gpsmonacogroup.com\/gamme\/medical\/masques-et-charlottes\/","name":"Masques et charlottes hygi\u00e9niques \u2013 Protection m\u00e9dicale - GPS Monaco Group","isPartOf":{"@id":"https:\/\/gpsmonacogroup.com\/it\/#website"},"description":"D\u00e9couvrez nos masques et charlottes hygi\u00e9niques, conformes aux exigences m\u00e9dicales, pour garantir protection et s\u00e9curit\u00e9 dans tous les environnements.","breadcrumb":{"@id":"https:\/\/gpsmonacogroup.com\/gamme\/medical\/masques-et-charlottes\/#breadcrumb"},"inLanguage":"it-IT"},{"@type":"BreadcrumbList","@id":"https:\/\/gpsmonacogroup.com\/gamme\/medical\/masques-et-charlottes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/gpsmonacogroup.com\/"},{"@type":"ListItem","position":2,"name":"Mat\u00e9riel M\u00e9dical","item":"https:\/\/gpsmonacogroup.com\/gamme\/medical\/"},{"@type":"ListItem","position":3,"name":"Masques et Charlottes"}]},{"@type":"WebSite","@id":"https:\/\/gpsmonacogroup.com\/it\/#website","url":"https:\/\/gpsmonacogroup.com\/it\/","name":"Gruppo GPS Monaco","description":"","publisher":{"@id":"https:\/\/gpsmonacogroup.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/gpsmonacogroup.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/gpsmonacogroup.com\/it\/#organization","name":"Gruppo GPS Monaco","url":"https:\/\/gpsmonacogroup.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/gpsmonacogroup.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/gpsmonacogroup.com\/wp-content\/uploads\/2024\/08\/logo-GPS-blanc.webp","contentUrl":"https:\/\/gpsmonacogroup.com\/wp-content\/uploads\/2024\/08\/logo-GPS-blanc.webp","width":211,"height":125,"caption":"GPS Monaco Group"},"image":{"@id":"https:\/\/gpsmonacogroup.com\/it\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/gpsmonacogroup.com\/it\/wp-json\/wp\/v2\/https:\/\/gpsmonacogroup.com\/gamme\/143","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gpsmonacogroup.com\/it\/wp-json\/wp\/v2\/https:\/\/gpsmonacogroup.com\/gamme"}],"about":[{"href":"https:\/\/gpsmonacogroup.com\/it\/wp-json\/wp\/v2\/taxonomies\/gamme"}],"up":[{"embeddable":true,"href":"https:\/\/gpsmonacogroup.com\/it\/wp-json\/wp\/v2\/https:\/\/gpsmonacogroup.com\/gamme\/94"}],"wp:post_type":[{"href":"https:\/\/gpsmonacogroup.com\/it\/wp-json\/wp\/v2\/catalogues?https:\/\/gpsmonacogroup.com\/gamme=143"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}