{"id":114,"count":10,"description":"","link":"https:\/\/gpsmonacogroup.com\/it\/gamme\/interieur\/salle-de-bain\/","name":"Bagno","slug":"salle-de-bain","taxonomy":"gamme","parent":85,"meta":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Salle de bain \u2013 Solutions \u00e9l\u00e9gantes et fonctionnelles - GPS Monaco Group<\/title>\n<meta name=\"description\" content=\"Explorez nos catalogues et trouvez des solutions pour cr\u00e9er une salle de bain \u00e9l\u00e9gante et fonctionnelle, alliant confort, design et praticit\u00e9.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/gpsmonacogroup.com\/it\/gamme\/interieur\/salle-de-bain\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Salle de bain \u2013 Solutions \u00e9l\u00e9gantes et fonctionnelles - GPS Monaco Group\" \/>\n<meta property=\"og:description\" content=\"Explorez nos catalogues et trouvez des solutions pour cr\u00e9er une salle de bain \u00e9l\u00e9gante et fonctionnelle, alliant confort, design et praticit\u00e9.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/gpsmonacogroup.com\/it\/gamme\/interieur\/salle-de-bain\/\" \/>\n<meta property=\"og:site_name\" content=\"GPS Monaco Group\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/gpsmonacogroup.com\\\/gamme\\\/interieur\\\/salle-de-bain\\\/\",\"url\":\"https:\\\/\\\/gpsmonacogroup.com\\\/gamme\\\/interieur\\\/salle-de-bain\\\/\",\"name\":\"Salle de bain \u2013 Solutions \u00e9l\u00e9gantes et fonctionnelles - GPS Monaco Group\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/gpsmonacogroup.com\\\/it\\\/#website\"},\"description\":\"Explorez nos catalogues et trouvez des solutions pour cr\u00e9er une salle de bain \u00e9l\u00e9gante et fonctionnelle, alliant confort, design et praticit\u00e9.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/gpsmonacogroup.com\\\/gamme\\\/interieur\\\/salle-de-bain\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/gpsmonacogroup.com\\\/gamme\\\/interieur\\\/salle-de-bain\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/gpsmonacogroup.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Int\u00e9rieur\",\"item\":\"https:\\\/\\\/gpsmonacogroup.com\\\/gamme\\\/interieur\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Salle de Bain\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/gpsmonacogroup.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/gpsmonacogroup.com\\\/it\\\/\",\"name\":\"GPS Monaco Group\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/gpsmonacogroup.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/gpsmonacogroup.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/gpsmonacogroup.com\\\/it\\\/#organization\",\"name\":\"GPS Monaco Group\",\"url\":\"https:\\\/\\\/gpsmonacogroup.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/gpsmonacogroup.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/gpsmonacogroup.com\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/logo-GPS-blanc.webp\",\"contentUrl\":\"https:\\\/\\\/gpsmonacogroup.com\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/logo-GPS-blanc.webp\",\"width\":211,\"height\":125,\"caption\":\"GPS Monaco Group\"},\"image\":{\"@id\":\"https:\\\/\\\/gpsmonacogroup.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Salle de bain \u2013 Solutions \u00e9l\u00e9gantes et fonctionnelles - GPS Monaco Group","description":"Explorez nos catalogues et trouvez des solutions pour cr\u00e9er une salle de bain \u00e9l\u00e9gante et fonctionnelle, alliant confort, design et praticit\u00e9.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/gpsmonacogroup.com\/it\/gamme\/interieur\/salle-de-bain\/","og_locale":"it_IT","og_type":"article","og_title":"Salle de bain \u2013 Solutions \u00e9l\u00e9gantes et fonctionnelles - GPS Monaco Group","og_description":"Explorez nos catalogues et trouvez des solutions pour cr\u00e9er une salle de bain \u00e9l\u00e9gante et fonctionnelle, alliant confort, design et praticit\u00e9.","og_url":"https:\/\/gpsmonacogroup.com\/it\/gamme\/interieur\/salle-de-bain\/","og_site_name":"GPS Monaco Group","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/gpsmonacogroup.com\/gamme\/interieur\/salle-de-bain\/","url":"https:\/\/gpsmonacogroup.com\/gamme\/interieur\/salle-de-bain\/","name":"Salle de bain \u2013 Solutions \u00e9l\u00e9gantes et fonctionnelles - GPS Monaco Group","isPartOf":{"@id":"https:\/\/gpsmonacogroup.com\/it\/#website"},"description":"Explorez nos catalogues et trouvez des solutions pour cr\u00e9er une salle de bain \u00e9l\u00e9gante et fonctionnelle, alliant confort, design et praticit\u00e9.","breadcrumb":{"@id":"https:\/\/gpsmonacogroup.com\/gamme\/interieur\/salle-de-bain\/#breadcrumb"},"inLanguage":"it-IT"},{"@type":"BreadcrumbList","@id":"https:\/\/gpsmonacogroup.com\/gamme\/interieur\/salle-de-bain\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/gpsmonacogroup.com\/"},{"@type":"ListItem","position":2,"name":"Int\u00e9rieur","item":"https:\/\/gpsmonacogroup.com\/gamme\/interieur\/"},{"@type":"ListItem","position":3,"name":"Salle de Bain"}]},{"@type":"WebSite","@id":"https:\/\/gpsmonacogroup.com\/it\/#website","url":"https:\/\/gpsmonacogroup.com\/it\/","name":"Gruppo GPS Monaco","description":"","publisher":{"@id":"https:\/\/gpsmonacogroup.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/gpsmonacogroup.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/gpsmonacogroup.com\/it\/#organization","name":"Gruppo GPS Monaco","url":"https:\/\/gpsmonacogroup.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/gpsmonacogroup.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/gpsmonacogroup.com\/wp-content\/uploads\/2024\/08\/logo-GPS-blanc.webp","contentUrl":"https:\/\/gpsmonacogroup.com\/wp-content\/uploads\/2024\/08\/logo-GPS-blanc.webp","width":211,"height":125,"caption":"GPS Monaco Group"},"image":{"@id":"https:\/\/gpsmonacogroup.com\/it\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/gpsmonacogroup.com\/it\/wp-json\/wp\/v2\/https:\/\/gpsmonacogroup.com\/gamme\/114","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gpsmonacogroup.com\/it\/wp-json\/wp\/v2\/https:\/\/gpsmonacogroup.com\/gamme"}],"about":[{"href":"https:\/\/gpsmonacogroup.com\/it\/wp-json\/wp\/v2\/taxonomies\/gamme"}],"up":[{"embeddable":true,"href":"https:\/\/gpsmonacogroup.com\/it\/wp-json\/wp\/v2\/https:\/\/gpsmonacogroup.com\/gamme\/85"}],"wp:post_type":[{"href":"https:\/\/gpsmonacogroup.com\/it\/wp-json\/wp\/v2\/catalogues?https:\/\/gpsmonacogroup.com\/gamme=114"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}