{"id":123,"count":7,"description":"","link":"https:\/\/gpsmonacogroup.com\/es\/gamme\/exterieur\/decoration-exterieur\/","name":"Decoraci\u00f3n exterior","slug":"decoration-exterieur","taxonomy":"gamme","parent":122,"meta":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>D\u00e9coration d&#039;ext\u00e9rieur \u00e9l\u00e9gante et tendance - GPS Monaco Group<\/title>\n<meta name=\"description\" content=\"Transformez vos espaces ext\u00e9rieurs avec nos accessoires de d\u00e9coration \u00e9l\u00e9gants et tendance. Parcourez nos catalogues pour cr\u00e9er un ext\u00e9rieur unique.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/gpsmonacogroup.com\/es\/gamme\/exterieur\/decoration-exterieur\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"D\u00e9coration d&#039;ext\u00e9rieur \u00e9l\u00e9gante et tendance - GPS Monaco Group\" \/>\n<meta property=\"og:description\" content=\"Transformez vos espaces ext\u00e9rieurs avec nos accessoires de d\u00e9coration \u00e9l\u00e9gants et tendance. Parcourez nos catalogues pour cr\u00e9er un ext\u00e9rieur unique.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/gpsmonacogroup.com\/es\/gamme\/exterieur\/decoration-exterieur\/\" \/>\n<meta property=\"og:site_name\" content=\"GPS Monaco Group\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/gpsmonacogroup.com\\\/gamme\\\/exterieur\\\/decoration-exterieur\\\/\",\"url\":\"https:\\\/\\\/gpsmonacogroup.com\\\/gamme\\\/exterieur\\\/decoration-exterieur\\\/\",\"name\":\"D\u00e9coration d'ext\u00e9rieur \u00e9l\u00e9gante et tendance - GPS Monaco Group\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/gpsmonacogroup.com\\\/it\\\/#website\"},\"description\":\"Transformez vos espaces ext\u00e9rieurs avec nos accessoires de d\u00e9coration \u00e9l\u00e9gants et tendance. Parcourez nos catalogues pour cr\u00e9er un ext\u00e9rieur unique.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/gpsmonacogroup.com\\\/gamme\\\/exterieur\\\/decoration-exterieur\\\/#breadcrumb\"},\"inLanguage\":\"es\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/gpsmonacogroup.com\\\/gamme\\\/exterieur\\\/decoration-exterieur\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/gpsmonacogroup.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ext\u00e9rieur\",\"item\":\"https:\\\/\\\/gpsmonacogroup.com\\\/gamme\\\/exterieur\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"D\u00e9coration d'Ext\u00e9rieur\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/gpsmonacogroup.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/gpsmonacogroup.com\\\/it\\\/\",\"name\":\"GPS Monaco Group\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/gpsmonacogroup.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/gpsmonacogroup.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/gpsmonacogroup.com\\\/it\\\/#organization\",\"name\":\"GPS Monaco Group\",\"url\":\"https:\\\/\\\/gpsmonacogroup.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/gpsmonacogroup.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/gpsmonacogroup.com\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/logo-GPS-blanc.webp\",\"contentUrl\":\"https:\\\/\\\/gpsmonacogroup.com\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/logo-GPS-blanc.webp\",\"width\":211,\"height\":125,\"caption\":\"GPS Monaco Group\"},\"image\":{\"@id\":\"https:\\\/\\\/gpsmonacogroup.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"D\u00e9coration d'ext\u00e9rieur \u00e9l\u00e9gante et tendance - GPS Monaco Group","description":"Transformez vos espaces ext\u00e9rieurs avec nos accessoires de d\u00e9coration \u00e9l\u00e9gants et tendance. Parcourez nos catalogues pour cr\u00e9er un ext\u00e9rieur unique.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/gpsmonacogroup.com\/es\/gamme\/exterieur\/decoration-exterieur\/","og_locale":"es_ES","og_type":"article","og_title":"D\u00e9coration d'ext\u00e9rieur \u00e9l\u00e9gante et tendance - GPS Monaco Group","og_description":"Transformez vos espaces ext\u00e9rieurs avec nos accessoires de d\u00e9coration \u00e9l\u00e9gants et tendance. Parcourez nos catalogues pour cr\u00e9er un ext\u00e9rieur unique.","og_url":"https:\/\/gpsmonacogroup.com\/es\/gamme\/exterieur\/decoration-exterieur\/","og_site_name":"GPS Monaco Group","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/gpsmonacogroup.com\/gamme\/exterieur\/decoration-exterieur\/","url":"https:\/\/gpsmonacogroup.com\/gamme\/exterieur\/decoration-exterieur\/","name":"D\u00e9coration d'ext\u00e9rieur \u00e9l\u00e9gante et tendance - GPS Monaco Group","isPartOf":{"@id":"https:\/\/gpsmonacogroup.com\/it\/#website"},"description":"Transformez vos espaces ext\u00e9rieurs avec nos accessoires de d\u00e9coration \u00e9l\u00e9gants et tendance. Parcourez nos catalogues pour cr\u00e9er un ext\u00e9rieur unique.","breadcrumb":{"@id":"https:\/\/gpsmonacogroup.com\/gamme\/exterieur\/decoration-exterieur\/#breadcrumb"},"inLanguage":"es"},{"@type":"BreadcrumbList","@id":"https:\/\/gpsmonacogroup.com\/gamme\/exterieur\/decoration-exterieur\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/gpsmonacogroup.com\/"},{"@type":"ListItem","position":2,"name":"Ext\u00e9rieur","item":"https:\/\/gpsmonacogroup.com\/gamme\/exterieur\/"},{"@type":"ListItem","position":3,"name":"D\u00e9coration d'Ext\u00e9rieur"}]},{"@type":"WebSite","@id":"https:\/\/gpsmonacogroup.com\/it\/#website","url":"https:\/\/gpsmonacogroup.com\/it\/","name":"Grupo GPS M\u00f3naco","description":"","publisher":{"@id":"https:\/\/gpsmonacogroup.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/gpsmonacogroup.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/gpsmonacogroup.com\/it\/#organization","name":"Grupo GPS M\u00f3naco","url":"https:\/\/gpsmonacogroup.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/gpsmonacogroup.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/gpsmonacogroup.com\/wp-content\/uploads\/2024\/08\/logo-GPS-blanc.webp","contentUrl":"https:\/\/gpsmonacogroup.com\/wp-content\/uploads\/2024\/08\/logo-GPS-blanc.webp","width":211,"height":125,"caption":"GPS Monaco Group"},"image":{"@id":"https:\/\/gpsmonacogroup.com\/it\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/gpsmonacogroup.com\/es\/wp-json\/wp\/v2\/https:\/\/gpsmonacogroup.com\/gamme\/123","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gpsmonacogroup.com\/es\/wp-json\/wp\/v2\/https:\/\/gpsmonacogroup.com\/gamme"}],"about":[{"href":"https:\/\/gpsmonacogroup.com\/es\/wp-json\/wp\/v2\/taxonomies\/gamme"}],"up":[{"embeddable":true,"href":"https:\/\/gpsmonacogroup.com\/es\/wp-json\/wp\/v2\/https:\/\/gpsmonacogroup.com\/gamme\/122"}],"wp:post_type":[{"href":"https:\/\/gpsmonacogroup.com\/es\/wp-json\/wp\/v2\/catalogues?https:\/\/gpsmonacogroup.com\/gamme=123"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}