{"id":112,"count":3,"description":"","link":"https:\/\/gpsmonacogroup.com\/en\/gamme\/construction\/cloisons-et-plafonds\/","name":"Partitions and Ceilings","slug":"cloisons-et-plafonds","taxonomy":"gamme","parent":66,"meta":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Cloisons et Plafonds - GPS Monaco Group<\/title>\n<meta name=\"description\" content=\"GPS Monaco Group propose des cloisons et plafonds robustes et esth\u00e9tiques, adapt\u00e9s aux besoins des projets de construction et d\u2019architecture.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/gpsmonacogroup.com\/en\/gamme\/construction\/cloisons-et-plafonds\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cloisons et Plafonds - GPS Monaco Group\" \/>\n<meta property=\"og:description\" content=\"GPS Monaco Group propose des cloisons et plafonds robustes et esth\u00e9tiques, adapt\u00e9s aux besoins des projets de construction et d\u2019architecture.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/gpsmonacogroup.com\/en\/gamme\/construction\/cloisons-et-plafonds\/\" \/>\n<meta property=\"og:site_name\" content=\"GPS Monaco Group\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/gpsmonacogroup.com\\\/gamme\\\/construction\\\/cloisons-et-plafonds\\\/\",\"url\":\"https:\\\/\\\/gpsmonacogroup.com\\\/gamme\\\/construction\\\/cloisons-et-plafonds\\\/\",\"name\":\"Cloisons et Plafonds - GPS Monaco Group\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/gpsmonacogroup.com\\\/it\\\/#website\"},\"description\":\"GPS Monaco Group propose des cloisons et plafonds robustes et esth\u00e9tiques, adapt\u00e9s aux besoins des projets de construction et d\u2019architecture.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/gpsmonacogroup.com\\\/gamme\\\/construction\\\/cloisons-et-plafonds\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/gpsmonacogroup.com\\\/gamme\\\/construction\\\/cloisons-et-plafonds\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/gpsmonacogroup.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Construction\",\"item\":\"https:\\\/\\\/gpsmonacogroup.com\\\/gamme\\\/construction\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Cloisons et Plafonds\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/gpsmonacogroup.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/gpsmonacogroup.com\\\/it\\\/\",\"name\":\"GPS Monaco Group\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/gpsmonacogroup.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/gpsmonacogroup.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/gpsmonacogroup.com\\\/it\\\/#organization\",\"name\":\"GPS Monaco Group\",\"url\":\"https:\\\/\\\/gpsmonacogroup.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/gpsmonacogroup.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/gpsmonacogroup.com\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/logo-GPS-blanc.webp\",\"contentUrl\":\"https:\\\/\\\/gpsmonacogroup.com\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/logo-GPS-blanc.webp\",\"width\":211,\"height\":125,\"caption\":\"GPS Monaco Group\"},\"image\":{\"@id\":\"https:\\\/\\\/gpsmonacogroup.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cloisons et Plafonds - GPS Monaco Group","description":"GPS Monaco Group propose des cloisons et plafonds robustes et esth\u00e9tiques, adapt\u00e9s aux besoins des projets de construction et d\u2019architecture.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/gpsmonacogroup.com\/en\/gamme\/construction\/cloisons-et-plafonds\/","og_locale":"en_GB","og_type":"article","og_title":"Cloisons et Plafonds - GPS Monaco Group","og_description":"GPS Monaco Group propose des cloisons et plafonds robustes et esth\u00e9tiques, adapt\u00e9s aux besoins des projets de construction et d\u2019architecture.","og_url":"https:\/\/gpsmonacogroup.com\/en\/gamme\/construction\/cloisons-et-plafonds\/","og_site_name":"GPS Monaco Group","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/gpsmonacogroup.com\/gamme\/construction\/cloisons-et-plafonds\/","url":"https:\/\/gpsmonacogroup.com\/gamme\/construction\/cloisons-et-plafonds\/","name":"Cloisons et Plafonds - GPS Monaco Group","isPartOf":{"@id":"https:\/\/gpsmonacogroup.com\/it\/#website"},"description":"GPS Monaco Group propose des cloisons et plafonds robustes et esth\u00e9tiques, adapt\u00e9s aux besoins des projets de construction et d\u2019architecture.","breadcrumb":{"@id":"https:\/\/gpsmonacogroup.com\/gamme\/construction\/cloisons-et-plafonds\/#breadcrumb"},"inLanguage":"en-GB"},{"@type":"BreadcrumbList","@id":"https:\/\/gpsmonacogroup.com\/gamme\/construction\/cloisons-et-plafonds\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/gpsmonacogroup.com\/"},{"@type":"ListItem","position":2,"name":"Construction","item":"https:\/\/gpsmonacogroup.com\/gamme\/construction\/"},{"@type":"ListItem","position":3,"name":"Cloisons et Plafonds"}]},{"@type":"WebSite","@id":"https:\/\/gpsmonacogroup.com\/it\/#website","url":"https:\/\/gpsmonacogroup.com\/it\/","name":"GPS Monaco Group,","description":"","publisher":{"@id":"https:\/\/gpsmonacogroup.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/gpsmonacogroup.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/gpsmonacogroup.com\/it\/#organization","name":"GPS Monaco Group,","url":"https:\/\/gpsmonacogroup.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/gpsmonacogroup.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/gpsmonacogroup.com\/wp-content\/uploads\/2024\/08\/logo-GPS-blanc.webp","contentUrl":"https:\/\/gpsmonacogroup.com\/wp-content\/uploads\/2024\/08\/logo-GPS-blanc.webp","width":211,"height":125,"caption":"GPS Monaco Group"},"image":{"@id":"https:\/\/gpsmonacogroup.com\/it\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/gpsmonacogroup.com\/en\/wp-json\/wp\/v2\/https:\/\/gpsmonacogroup.com\/gamme\/112","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gpsmonacogroup.com\/en\/wp-json\/wp\/v2\/https:\/\/gpsmonacogroup.com\/gamme"}],"about":[{"href":"https:\/\/gpsmonacogroup.com\/en\/wp-json\/wp\/v2\/taxonomies\/gamme"}],"up":[{"embeddable":true,"href":"https:\/\/gpsmonacogroup.com\/en\/wp-json\/wp\/v2\/https:\/\/gpsmonacogroup.com\/gamme\/66"}],"wp:post_type":[{"href":"https:\/\/gpsmonacogroup.com\/en\/wp-json\/wp\/v2\/catalogues?https:\/\/gpsmonacogroup.com\/gamme=112"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}